{"id":18,"count":1,"description":"","link":"https:\/\/exportis.fr\/fr\/category\/etude-de-cas\/","name":"\u00c9tude de cas","slug":"etude-de-cas","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00c9tude de cas Archives - exportis<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/exportis.fr\/category\/case-study\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00c9tude de cas Archives - exportis\" \/>\n<meta property=\"og:url\" content=\"https:\/\/exportis.fr\/category\/case-study\/\" \/>\n<meta property=\"og:site_name\" content=\"exportis\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/exportis.fr\/category\/case-study\/\",\"url\":\"https:\/\/exportis.fr\/category\/case-study\/\",\"name\":\"\u00c9tude de cas Archives - exportis\",\"isPartOf\":{\"@id\":\"https:\/\/exportis.fr\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/exportis.fr\/category\/case-study\/#breadcrumb\"},\"inLanguage\":\"fr-FR\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/exportis.fr\/category\/case-study\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/exportis.fr\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Case Study\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/exportis.fr\/#website\",\"url\":\"https:\/\/exportis.fr\/\",\"name\":\"exportis\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/exportis.fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/exportis.fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/exportis.fr\/#organization\",\"name\":\"exportis\",\"url\":\"https:\/\/exportis.fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/exportis.fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/exportis.fr\/wp-content\/uploads\/2025\/08\/exporties-logo.png\",\"contentUrl\":\"https:\/\/exportis.fr\/wp-content\/uploads\/2025\/08\/exporties-logo.png\",\"width\":800,\"height\":193,\"caption\":\"exportis\"},\"image\":{\"@id\":\"https:\/\/exportis.fr\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00c9tude de cas Archives - exportis","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/exportis.fr\/category\/case-study\/","og_locale":"fr_FR","og_type":"article","og_title":"\u00c9tude de cas Archives - exportis","og_url":"https:\/\/exportis.fr\/category\/case-study\/","og_site_name":"exportis","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/exportis.fr\/category\/case-study\/","url":"https:\/\/exportis.fr\/category\/case-study\/","name":"\u00c9tude de cas Archives - exportis","isPartOf":{"@id":"https:\/\/exportis.fr\/#website"},"breadcrumb":{"@id":"https:\/\/exportis.fr\/category\/case-study\/#breadcrumb"},"inLanguage":"fr-FR"},{"@type":"BreadcrumbList","@id":"https:\/\/exportis.fr\/category\/case-study\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/exportis.fr\/fr\/"},{"@type":"ListItem","position":2,"name":"Case Study"}]},{"@type":"WebSite","@id":"https:\/\/exportis.fr\/#website","url":"https:\/\/exportis.fr\/","name":"exportis","description":"","publisher":{"@id":"https:\/\/exportis.fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/exportis.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/exportis.fr\/#organization","name":"exportis","url":"https:\/\/exportis.fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/exportis.fr\/#\/schema\/logo\/image\/","url":"https:\/\/exportis.fr\/wp-content\/uploads\/2025\/08\/exporties-logo.png","contentUrl":"https:\/\/exportis.fr\/wp-content\/uploads\/2025\/08\/exporties-logo.png","width":800,"height":193,"caption":"exportis"},"image":{"@id":"https:\/\/exportis.fr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/exportis.fr\/fr\/wp-json\/wp\/v2\/categories\/18","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/exportis.fr\/fr\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/exportis.fr\/fr\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/exportis.fr\/fr\/wp-json\/wp\/v2\/posts?categories=18"},{"href":"https:\/\/exportis.fr\/fr\/wp-json\/wp\/v2\/services?categories=18"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}